{"id":809,"date":"2026-03-16T18:04:28","date_gmt":"2026-03-16T17:04:28","guid":{"rendered":"https:\/\/design.superstudioevents.com\/?post_type=espositore&#038;p=809"},"modified":"2026-03-30T09:32:27","modified_gmt":"2026-03-30T07:32:27","slug":"zade-design-crafts-studio","status":"publish","type":"espositore","link":"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/zade-design-crafts-studio\/","title":{"rendered":"Zade Design"},"content":{"rendered":"<section class=\"contenuto-espositore\">\r\n  <div class=\"back-container fade-in-right\">\r\n    <p id=\"espositori-back-button\"> <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n        <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n      <\/svg>\r\n      BACK\r\n    <\/p>\r\n    <!-- Bottone back anno\r\n                 <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2026\/\">\r\n          <svg width=\"100%\" height=\"100%\" viewBox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n            <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n          <\/svg>\r\n          SCOPRI GLI ESPOSITORI\r\n        <\/a>\r\n           \r\n    -->\r\n  <\/div>\r\n  <div class=\"contenuto-espositore-container fade-in-up\">\r\n          <div class=\"contenuto-espositore-gallery fade-in-left\">\r\n        <div class=\"swiper-wrapper\">\r\n                      <figure class=\"swiper-slide\">\r\n              <img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/0003-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>            <\/figure>\r\n                      <figure class=\"swiper-slide\">\r\n              <img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT-1024x683.jpg 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT-450x300.jpg 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT-300x200.jpg 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT-768x512.jpg 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT-1536x1024.jpg 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT-18x12.jpg 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/DELIGHT.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>            <\/figure>\r\n                  <\/div>\r\n      <\/div>\r\n    \r\n    <div class=\"contenuto-espositore-testi\">\r\n              <h2 class=\"character-animation\">Zade Design<\/h2>\r\n        <h3 class=\"character-animation\">Delight Coffee Table (Collezione Teardrop) &amp; De\u011firmen Table Lamp<\/h3>\r\n      \r\n              <div class=\"contenuto-espositore-designer\">\r\n          <p>Designer<\/p>\r\n          <p>Zade Design Crafts Studio, Nadire Ertu\u011frul<\/p>\r\n        <\/div>\r\n      \r\n\r\n              <div class=\"contenuto-espositore-text\">\r\n          <p><span style=\"font-weight: 400;\">Nature and craftsmanship are two sources that nourish the human soul, ignite creativity, and awaken aesthetic senses. Each of these elements, fascinating on its own, when brought together, creates true harmony and beauty. It is from this union that the inspiration for the Teardrop Coffee Table was born. <\/span>For the studio, the most important details were ensuring that each new product is unique, personalized, and crafted with different textures. The masterpieces shaped with important craftsmanship and handmade details, which encompass the creativity of carefully processed materials, align perfectly with the studio\u2019s design philosophy. By bringing out the beauty from the essence of three different materials and showcasing the unique abilities of the human hand, we ensured that each product is distinct from the others.<\/p>\n<p>The Teardrop Coffee Table is a perfect example of art and craftsmanship, combining metal, glass, and ceramic elements with great skill. The blowing glass technique ensures the elegant and unique creation of the glass legs, while the ceramic top offers a unique creation. The artisans skillfully combine these different materials to create a contemporary furniture piece that offers both aesthetics and functionality, making each Teardrop Coffee Table personalized for those who seek art and functionality in their homes.<\/p>\n<p>&nbsp;<\/p>\n        <\/div>\r\n      \r\n              <ul class=\"contenuto-espositore-links\">\r\n                      <li class=\"contenuto-espositore-links-item\">\r\n                              <a href=\"https:\/\/www.instagram.com\/zade_design\/\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n                  <span class=\"contenuto-espositore-link-title\">INSTAGRAM<\/span>                  <span class=\"contenuto-espositore-link-text\">@zade_design<\/span>                <\/a>\r\n                          <\/li>\r\n                      <li class=\"contenuto-espositore-links-item\">\r\n                              <a href=\"https:\/\/zadedesign.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">\r\n                  <span class=\"contenuto-espositore-link-title\">WEBSITE<\/span>                  <span class=\"contenuto-espositore-link-text\">www.zadedesign.com<\/span>                <\/a>\r\n                          <\/li>\r\n                  <\/ul>\r\n          <\/div>\r\n  <\/div>\r\n<\/section>","protected":false},"featured_media":1695,"menu_order":0,"template":"","meta":{"_acf_changed":true},"anno":[47],"categoria-espositore":[19],"class_list":["post-809","espositore","type-espositore","status-publish","has-post-thumbnail","hentry","anno-47","categoria-espositore-superplayground"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zade Design - Superstudio Design<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zade Design - Superstudio Design\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/zade-design-crafts-studio\/\" \/>\n<meta property=\"og:site_name\" content=\"Superstudio Design\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T07:32:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/0003-e1774855944609.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/\",\"name\":\"Zade Design - Superstudio Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/0003-e1774855944609.jpg\",\"datePublished\":\"2026-03-16T17:04:28+00:00\",\"dateModified\":\"2026-03-30T07:32:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/0003-e1774855944609.jpg\",\"contentUrl\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/0003-e1774855944609.jpg\",\"width\":720,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositore\\\/zade-design-crafts-studio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espositori\",\"item\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/espositori\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zade Design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#website\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/\",\"name\":\"Superstudio Design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#organization\",\"name\":\"SuperstudioDesign\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Superstudio-scritta.svg\",\"contentUrl\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Superstudio-scritta.svg\",\"caption\":\"SuperstudioDesign\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/superstudio.design\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zade Design - Superstudio Design","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Zade Design - Superstudio Design","og_url":"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/zade-design-crafts-studio\/","og_site_name":"Superstudio Design","article_modified_time":"2026-03-30T07:32:27+00:00","og_image":[{"width":720,"height":900,"url":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/0003-e1774855944609.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/","url":"https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/","name":"Zade Design - Superstudio Design","isPartOf":{"@id":"https:\/\/staging.design.superstudioevents.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/#primaryimage"},"image":{"@id":"https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/0003-e1774855944609.jpg","datePublished":"2026-03-16T17:04:28+00:00","dateModified":"2026-03-30T07:32:27+00:00","breadcrumb":{"@id":"https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/#primaryimage","url":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/0003-e1774855944609.jpg","contentUrl":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/0003-e1774855944609.jpg","width":720,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/staging.design.superstudioevents.com\/espositore\/zade-design-crafts-studio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.design.superstudioevents.com\/"},{"@type":"ListItem","position":2,"name":"Espositori","item":"https:\/\/staging.design.superstudioevents.com\/espositori\/"},{"@type":"ListItem","position":3,"name":"Zade Design"}]},{"@type":"WebSite","@id":"https:\/\/staging.design.superstudioevents.com\/#website","url":"https:\/\/staging.design.superstudioevents.com\/","name":"Superstudio Design","description":"","publisher":{"@id":"https:\/\/staging.design.superstudioevents.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.design.superstudioevents.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/staging.design.superstudioevents.com\/#organization","name":"SuperstudioDesign","url":"https:\/\/staging.design.superstudioevents.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/staging.design.superstudioevents.com\/#\/schema\/logo\/image\/","url":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2025\/12\/Superstudio-scritta.svg","contentUrl":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2025\/12\/Superstudio-scritta.svg","caption":"SuperstudioDesign"},"image":{"@id":"https:\/\/staging.design.superstudioevents.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/superstudio.design\/"]}]}},"_links":{"self":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/espositore\/809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/espositore"}],"about":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/types\/espositore"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/media\/1695"}],"wp:attachment":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/media?parent=809"}],"wp:term":[{"taxonomy":"anno","embeddable":true,"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/anno?post=809"},{"taxonomy":"categoria-espositore","embeddable":true,"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/categoria-espositore?post=809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}