{"id":1415,"date":"2026-02-23T17:06:25","date_gmt":"2026-02-23T16:06:25","guid":{"rendered":"https:\/\/design.superstudioevents.com\/?page_id=1415"},"modified":"2026-02-24T15:21:55","modified_gmt":"2026-02-24T14:21:55","slug":"superdesign-show-archivio","status":"publish","type":"page","link":"https:\/\/staging.design.superstudioevents.com\/en\/superdesign-show-archivio\/","title":{"rendered":"Archivio"},"content":{"rendered":"<section class=\"galleria-espositori\">\r\n      <h2 class=\"character-animation\">archive<\/h2>\r\n  \r\n          <div class=\"galleria-espositori-wrapper fade-in\">\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/3m\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"675\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-450x675.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Torre di legno di Matteo Thun\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-450x675.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-683x1024.webp 683w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M.webp 720w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              3M               <span class=\"galleria-espositori-anno\">2019<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/agc-asahi-glass\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"AGC Asahi a Superstudio\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              AGC Asahi Glass               <span class=\"galleria-espositori-anno\">2016<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/citizen\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Citizen\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              CITIZEN               <span class=\"galleria-espositori-anno\">2016<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/dassaultsystemes\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"675\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-450x675.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Art installation by Dassault Systemes\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-450x675.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-683x1024.webp 683w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes.webp 720w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Dassault Syst\u00e8mes               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/agc-asahi-glass-2\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Fondazione Biohabitat\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Fondazione Biohabitat               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/geberit\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Geberit al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Geberit               <span class=\"galleria-espositori-anno\">2025<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/glo\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Toiletpaper\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              GLO\u2122               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/haier-europe\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Haier Europe\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Haier Europe               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/istituto-marangoni\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione dell&#039;Istituto Marangoni al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Istituto Marangoni               <span class=\"galleria-espositori-anno\">2023<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/kawai\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Pianoforte, Kawai\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              KAWAI               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/korea-craft-and-design-foundation\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione della Korea Craft Design Foundation\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Korea Craft &amp; Design Foundation               <span class=\"galleria-espositori-anno\">2019<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/lexus\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Lexus\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Lexus               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/nendo\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Mostra di Nendo\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Nendo               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/nichelcromlab-2\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Nichelcrom Lab al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              NichelcromLab               <span class=\"galleria-espositori-anno\">2024<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/samsung\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Samsung al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Samsung Electronics               <span class=\"galleria-espositori-anno\">2023<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/3m\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"675\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-450x675.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Torre di legno di Matteo Thun\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-450x675.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-683x1024.webp 683w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M.webp 720w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              3M               <span class=\"galleria-espositori-anno\">2019<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/agc-asahi-glass\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"AGC Asahi a Superstudio\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              AGC Asahi Glass               <span class=\"galleria-espositori-anno\">2016<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/citizen\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Citizen\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              CITIZEN               <span class=\"galleria-espositori-anno\">2016<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/dassaultsystemes\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"675\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-450x675.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Art installation by Dassault Systemes\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-450x675.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-683x1024.webp 683w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes.webp 720w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Dassault Syst\u00e8mes               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/agc-asahi-glass-2\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Fondazione Biohabitat\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Fondazione Biohabitat               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/geberit\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Geberit al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Geberit               <span class=\"galleria-espositori-anno\">2025<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/glo\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Toiletpaper\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              GLO\u2122               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/haier-europe\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Haier Europe\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Haier Europe               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/istituto-marangoni\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione dell&#039;Istituto Marangoni al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Istituto Marangoni               <span class=\"galleria-espositori-anno\">2023<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/kawai\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Pianoforte, Kawai\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              KAWAI               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/korea-craft-and-design-foundation\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione della Korea Craft Design Foundation\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Korea Craft &amp; Design Foundation               <span class=\"galleria-espositori-anno\">2019<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/lexus\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Lexus\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Lexus               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/nendo\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Mostra di Nendo\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Nendo               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/nichelcromlab-2\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Nichelcrom Lab al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              NichelcromLab               <span class=\"galleria-espositori-anno\">2024<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/samsung\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Samsung al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Samsung Electronics               <span class=\"galleria-espositori-anno\">2023<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/3m\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"675\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-450x675.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Torre di legno di Matteo Thun\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-450x675.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-683x1024.webp 683w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-MatteoThun_3M.webp 720w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              3M               <span class=\"galleria-espositori-anno\">2019<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/agc-asahi-glass\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"AGC Asahi a Superstudio\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-AGC-Asahi.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              AGC Asahi Glass               <span class=\"galleria-espositori-anno\">2016<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/citizen\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Citizen\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2016-Citizen.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              CITIZEN               <span class=\"galleria-espositori-anno\">2016<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/dassaultsystemes\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"675\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-450x675.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Art installation by Dassault Systemes\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-450x675.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-683x1024.webp 683w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Dassault-Systemes.webp 720w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Dassault Syst\u00e8mes               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/agc-asahi-glass-2\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Fondazione Biohabitat\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Fondazione-Biohabitat.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Fondazione Biohabitat               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/geberit\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Geberit al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2025-Geberit.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Geberit               <span class=\"galleria-espositori-anno\">2025<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/glo\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Toiletpaper\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-TOILETPAPER-GLO.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              GLO\u2122               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/haier-europe\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Haier Europe\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Haier-Europe.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Haier Europe               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/istituto-marangoni\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione dell&#039;Istituto Marangoni al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Istituto-Marangoni.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Istituto Marangoni               <span class=\"galleria-espositori-anno\">2023<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/kawai\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Pianoforte, Kawai\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Kawai.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              KAWAI               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/korea-craft-and-design-foundation\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione della Korea Craft Design Foundation\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2019-KOREA-CRAFT-DESIGN-FOUNDATION.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Korea Craft &amp; Design Foundation               <span class=\"galleria-espositori-anno\">2019<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/lexus\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"676\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-450x676.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Lexus\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-450x676.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-682x1024.webp 682w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-200x300.webp 200w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus-8x12.webp 8w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2022-Lexus.webp 719w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Lexus               <span class=\"galleria-espositori-anno\">2022<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/nendo\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Mostra di Nendo\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2018-Nendo.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Nendo               <span class=\"galleria-espositori-anno\">2018<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/nichelcromlab-2\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Nichelcrom Lab al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2024-NichelcromLab.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              NichelcromLab               <span class=\"galleria-espositori-anno\">2024<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n              <article class=\"galleria-espositori-slide\">\r\n          <a class=\"galleria-espositori-link\" href=\"https:\/\/staging.design.superstudioevents.com\/en\/espositore\/samsung\/\">\r\n                          <figure>\r\n                <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-450x300.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Installazione di Samsung al Superdesign Show\" srcset=\"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-450x300.webp 450w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-1024x683.webp 1024w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-300x200.webp 300w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-768x512.webp 768w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-1536x1024.webp 1536w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung-18x12.webp 18w, https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2026\/02\/Superdesign-Show-2023-Samsung.webp 1620w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>              <\/figure>\r\n                        <h3>\r\n              Samsung Electronics               <span class=\"galleria-espositori-anno\">2023<\/span>            <\/h3>\r\n          <\/a>\r\n        <\/article>\r\n          <\/div>\r\n  <\/section>\n\n\r\n<section class=\"archivio-anni\">\r\n      <ul class=\"archivio-anni-list fade-in-right-stagger-cont\">\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2026\/\">SUPERDESIGNSHOW 2026            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2025\/\">SUPERDESIGNSHOW 2025            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2024\/\">SUPERDESIGNSHOW 2024            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2023\/\">SUPERDESIGNSHOW 2023            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2022\/\">SUPERDESIGNSHOW 2022            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2019\/\">SUPERDESIGNSHOW 2019            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2018\/\">SUPERDESIGNSHOW 2018            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n              <li class=\"archivio-anni-item\">\r\n          <a href=\"https:\/\/staging.design.superstudioevents.com\/en\/anno\/2016\/\">SUPERDESIGNSHOW 2016            <svg width=\"100%\" height=\"100%\" viewbox=\"0 0 94 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n              <path d=\"M93.0607 12.1066C93.6464 11.5208 93.6464 10.571 93.0607 9.98525L83.5147 0.439304C82.9289 -0.146483 81.9792 -0.146483 81.3934 0.439304C80.8076 1.02509 80.8076 1.97484 81.3934 2.56062L89.8787 11.0459L81.3934 19.5312C80.8076 20.117 80.8076 21.0667 81.3934 21.6525C81.9792 22.2383 82.9289 22.2383 83.5147 21.6525L93.0607 12.1066ZM0 11.0459L-1.31134e-07 12.5459L92 12.5459L92 11.0459L92 9.54591L1.31134e-07 9.5459L0 11.0459Z\" fill=\"white\" \/>\r\n            <\/svg><\/a>\r\n        <\/li>\r\n          <\/ul>\r\n  <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1415","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archivio - Superdesign Show (ora Superstudio Design)<\/title>\n<meta name=\"description\" content=\"Archivio ufficiale del Superdesign Show, oggi Superstudio Design. Scopri le edizioni precedenti, i designer e i brand protagonisti negli anni fino al 2025.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archivio - Superdesign Show (ora Superstudio Design)\" \/>\n<meta property=\"og:description\" content=\"Archivio ufficiale del Superdesign Show, oggi Superstudio Design. Scopri le edizioni precedenti, i designer e i brand protagonisti negli anni fino al 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.design.superstudioevents.com\/en\/superdesign-show-archivio\/\" \/>\n<meta property=\"og:site_name\" content=\"Superstudio Design\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T14:21:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/superdesign-show-archivio\\\/\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/superdesign-show-archivio\\\/\",\"name\":\"Archivio - Superdesign Show (ora Superstudio Design)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#website\"},\"datePublished\":\"2026-02-23T16:06:25+00:00\",\"dateModified\":\"2026-02-24T14:21:55+00:00\",\"description\":\"Archivio ufficiale del Superdesign Show, oggi Superstudio Design. Scopri le edizioni precedenti, i designer e i brand protagonisti negli anni fino al 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/superdesign-show-archivio\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.design.superstudioevents.com\\\/superdesign-show-archivio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/superdesign-show-archivio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#website\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/\",\"name\":\"Superstudio Design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#organization\",\"name\":\"SuperstudioDesign\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Superstudio-scritta.svg\",\"contentUrl\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Superstudio-scritta.svg\",\"caption\":\"SuperstudioDesign\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.design.superstudioevents.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/superstudio.design\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archivio - Superdesign Show (ora Superstudio Design)","description":"Archivio ufficiale del Superdesign Show, oggi Superstudio Design. Scopri le edizioni precedenti, i designer e i brand protagonisti negli anni fino al 2025.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Archivio - Superdesign Show (ora Superstudio Design)","og_description":"Archivio ufficiale del Superdesign Show, oggi Superstudio Design. Scopri le edizioni precedenti, i designer e i brand protagonisti negli anni fino al 2025.","og_url":"https:\/\/staging.design.superstudioevents.com\/en\/superdesign-show-archivio\/","og_site_name":"Superstudio Design","article_modified_time":"2026-02-24T14:21:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.design.superstudioevents.com\/superdesign-show-archivio\/","url":"https:\/\/staging.design.superstudioevents.com\/superdesign-show-archivio\/","name":"Archivio - Superdesign Show (ora Superstudio Design)","isPartOf":{"@id":"https:\/\/staging.design.superstudioevents.com\/#website"},"datePublished":"2026-02-23T16:06:25+00:00","dateModified":"2026-02-24T14:21:55+00:00","description":"Archivio ufficiale del Superdesign Show, oggi Superstudio Design. Scopri le edizioni precedenti, i designer e i brand protagonisti negli anni fino al 2025.","breadcrumb":{"@id":"https:\/\/staging.design.superstudioevents.com\/superdesign-show-archivio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.design.superstudioevents.com\/superdesign-show-archivio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.design.superstudioevents.com\/superdesign-show-archivio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.design.superstudioevents.com\/"},{"@type":"ListItem","position":2,"name":"Archivio"}]},{"@type":"WebSite","@id":"https:\/\/staging.design.superstudioevents.com\/#website","url":"https:\/\/staging.design.superstudioevents.com\/","name":"Superstudio Design","description":"","publisher":{"@id":"https:\/\/staging.design.superstudioevents.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.design.superstudioevents.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/staging.design.superstudioevents.com\/#organization","name":"SuperstudioDesign","url":"https:\/\/staging.design.superstudioevents.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/staging.design.superstudioevents.com\/#\/schema\/logo\/image\/","url":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2025\/12\/Superstudio-scritta.svg","contentUrl":"https:\/\/staging.design.superstudioevents.com\/wp-content\/uploads\/2025\/12\/Superstudio-scritta.svg","caption":"SuperstudioDesign"},"image":{"@id":"https:\/\/staging.design.superstudioevents.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/superstudio.design\/"]}]}},"_links":{"self":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/pages\/1415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/comments?post=1415"}],"version-history":[{"count":1,"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/pages\/1415\/revisions"}],"predecessor-version":[{"id":1416,"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/pages\/1415\/revisions\/1416"}],"wp:attachment":[{"href":"https:\/\/staging.design.superstudioevents.com\/en\/wp-json\/wp\/v2\/media?parent=1415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}